{"id":13124,"count":1,"description":"","link":"https:\/\/www.kasetkaoklai.com\/home\/tag\/%e0%b8%8b%e0%b9%88%e0%b8%ad%e0%b8%a1%e0%b8%9d%e0%b8%b2%e0%b8%a2%e0%b8%8a%e0%b8%b0%e0%b8%a5%e0%b8%ad%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%a3%e0%b8%ad%e0%b8%9d%e0%b8%99\/","name":"\u0e0b\u0e48\u0e2d\u0e21\u0e1d\u0e32\u0e22\u0e0a\u0e30\u0e25\u0e2d\u0e19\u0e49\u0e33\u0e23\u0e2d\u0e1d\u0e19","slug":"%e0%b8%8b%e0%b9%88%e0%b8%ad%e0%b8%a1%e0%b8%9d%e0%b8%b2%e0%b8%a2%e0%b8%8a%e0%b8%b0%e0%b8%a5%e0%b8%ad%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%a3%e0%b8%ad%e0%b8%9d%e0%b8%99","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/tags\/13124"}],"collection":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts?tags=13124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}