{"id":65324,"date":"2025-12-26T18:29:36","date_gmt":"2025-12-26T11:29:36","guid":{"rendered":"https:\/\/www.kasetkaoklai.com\/home\/?p=65324"},"modified":"2025-12-26T18:29:37","modified_gmt":"2025-12-26T11:29:37","slug":"%e0%b8%a3%e0%b8%a1%e0%b8%a7-%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%99%e0%b8%b1%e0%b8%aa-%e0%b9%80%e0%b8%9c%e0%b8%a2-%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b8%8a%e0%b8%aa%e0%b8%a7","status":"publish","type":"post","link":"https:\/\/www.kasetkaoklai.com\/home\/2025\/12\/%e0%b8%a3%e0%b8%a1%e0%b8%a7-%e0%b8%98%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%99%e0%b8%b1%e0%b8%aa-%e0%b9%80%e0%b8%9c%e0%b8%a2-%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b8%8a%e0%b8%aa%e0%b8%a7\/","title":{"rendered":"\u0e23\u0e21\u0e27.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e2a \u0e40\u0e1c\u0e22 \u0e07\u0e32\u0e19\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e04\u0e37\u0e1a\u0e41\u0e25\u0e49\u0e27\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 43 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e2d\u0e14\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19"},"content":{"rendered":"\n<p><strong>\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e01 \u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e2a \u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e1c\u0e48\u0e32 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c<\/strong> \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e1e.\u0e28. 2569 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 1\/2568 \u0e42\u0e14\u0e22\u0e21\u0e35 <strong>\u0e19\u0e32\u0e22\u0e27\u0e34\u0e13\u0e30\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e48\u0e07\u0e2a\u0e38\u0e02 \u0e1b\u0e25\u0e31\u0e14\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c<\/strong> \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e2d\u0e32\u0e17\u0e34 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c (135) \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (Zoom Meeting)<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" data-id=\"65328\"  src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471296_0-1024x683.jpg\" alt=\"\u0e23\u0e21\u0e27.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e2a \u0e40\u0e1c\u0e22 \u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e1e.\u0e28.2569 \u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e25\u0e49\u0e27\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 43 \n\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e2d\u0e14\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\" class=\"wp-image-65328\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471296_0-1024x683.jpg 1024w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471296_0-500x333.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471296_0-1536x1024.jpg 1536w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471296_0-696x464.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471296_0-1068x712.jpg 1068w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471296_0-630x420.jpg 630w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471296_0.jpg 1567w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>\u0e23\u0e21\u0e27.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e2a \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e1e.\u0e28.2569 (Udon Thani International Horticultural Expo 2026) \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07 \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e49\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e08\u0e32\u0e01\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2b\u0e23\u0e37\u0e2d AIPH (The International Association of Horticultural Producers \u2013 AIPH) \u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e14\u0e49\u0e27\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e32\u0e01\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e4c \u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 43 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e21\u0e35\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2569 \u2013 14 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2570 \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e17\u0e35\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e32\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e40\u0e27\u0e17\u0e35\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07 \u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e25\u0e44\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"682\" data-id=\"65325\"  src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471297_0-1024x682.jpg\" alt=\"\u0e23\u0e21\u0e27.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e2a \u0e40\u0e1c\u0e22 \u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e1e.\u0e28.2569 \u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e25\u0e49\u0e27\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 43 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e2d\u0e14\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\" class=\"wp-image-65325\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471297_0-1024x682.jpg 1024w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471297_0-500x333.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471297_0-1536x1023.jpg 1536w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471297_0-696x464.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471297_0-1068x712.jpg 1068w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471297_0-630x420.jpg 630w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471297_0.jpg 1567w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" data-id=\"65329\"  src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471298_0-1024x683.jpg\" alt=\"\u0e23\u0e21\u0e27.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e2a \u0e40\u0e1c\u0e22 \u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e1e.\u0e28.2569 \u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e25\u0e49\u0e27\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 43 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e2d\u0e14\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\" class=\"wp-image-65329\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471298_0-1024x683.jpg 1024w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471298_0-500x333.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471298_0-1536x1024.jpg 1536w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471298_0-696x464.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471298_0-1068x712.jpg 1068w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471298_0-630x420.jpg 630w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471298_0.jpg 1567w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>\u201c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e17\u0e32\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2f \u0e41\u0e25\u0e30\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e14\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u201d \u0e23\u0e21\u0e27.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e2a \u0e01\u0e25\u0e48\u0e32\u0e27<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" data-id=\"65326\"  src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471309_0-1024x683.jpg\" alt=\"\u0e23\u0e21\u0e27.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e2a \u0e40\u0e1c\u0e22 \u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19\u0e42\u0e25\u0e01 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e1e.\u0e28.2569 \u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e25\u0e49\u0e27\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 43 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e2d\u0e14\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\" class=\"wp-image-65326\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471309_0-1024x683.jpg 1024w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471309_0-500x333.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471309_0-1536x1024.jpg 1536w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471309_0-696x464.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471309_0-1068x712.jpg 1068w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471309_0-630x420.jpg 630w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/12\/1471309_0.jpg 1567w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e01 \u0e18\u0e23\u0e23\u0e21\u0e19\u0e31\u0e2a \u0e1e\u0e23\u0e2b\u0e21\u0e40\u0e1c\u0e48\u0e32 \u0e23\u0e2d\u0e07\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":65327,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[51,48],"tags":[19876],"_links":{"self":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts\/65324"}],"collection":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/comments?post=65324"}],"version-history":[{"count":1,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts\/65324\/revisions"}],"predecessor-version":[{"id":65330,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts\/65324\/revisions\/65330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/media\/65327"}],"wp:attachment":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/media?parent=65324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/categories?post=65324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/tags?post=65324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}