{"id":64563,"date":"2025-11-09T15:38:06","date_gmt":"2025-11-09T08:38:06","guid":{"rendered":"https:\/\/www.kasetkaoklai.com\/home\/?p=64563"},"modified":"2025-11-09T16:29:11","modified_gmt":"2025-11-09T09:29:11","slug":"%e0%b8%8a%e0%b8%a5%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%a3%e0%b9%88%e0%b8%87%e0%b9%81%e0%b8%81%e0%b9%89%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%87-%e0%b8%9c%e0%b8%b8%e0%b8%94","status":"publish","type":"post","link":"https:\/\/www.kasetkaoklai.com\/home\/2025\/11\/%e0%b8%8a%e0%b8%a5%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%a3%e0%b9%88%e0%b8%87%e0%b9%81%e0%b8%81%e0%b9%89%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%87-%e0%b8%9c%e0%b8%b8%e0%b8%94\/","title":{"rendered":"\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e40\u0e23\u0e48\u0e07\u0e41\u0e01\u0e49\u0e41\u0e25\u0e49\u0e07! \u0e1c\u0e38\u0e14 4 \u0e1b\u0e15\u0e23.\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 &#8220;\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01-\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23-\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c&#8221; \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e19\u0e49\u0e33 142 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e22\u0e34\u0e49\u0e21\u0e23\u0e31\u0e1a 129,500 \u0e44\u0e23\u0e48"},"content":{"rendered":"\n<p><strong>\u0e02\u0e48\u0e32\u0e27\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\/\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 (6-7 \u0e1e.\u0e22.68)<\/strong> &#8211; \u0e01\u0e23\u0e21\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e40\u0e23\u0e48\u0e07\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19 4 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19\u0e43\u0e19\u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19\u00a0 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e20\u0e31\u0e22\u0e41\u0e25\u0e49\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e17\u0e01\u0e20\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e04\u0e32\u0e14\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e43\u0e19\u0e25\u0e33\u0e19\u0e49\u0e33\u0e44\u0e14\u0e49\u0e01\u0e27\u0e48\u0e32 142 \u0e25\u0e49\u0e32\u0e19\u0e25\u0e39\u0e01\u0e1a\u0e32\u0e28\u0e01\u0e4c\u0e40\u0e21\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e01\u0e27\u0e48\u0e32 1.2 \u0e41\u0e2a\u0e19\u0e44\u0e23\u0e48 (\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e0a\u0e21\u0e08\u0e32\u0e01\u0e04\u0e25\u0e34\u0e1b\u0e25\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49)<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u0e01\u0e23\u0e21\u0e0a\u0e25\u0e2f \u0e1c\u0e38\u0e14 4 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e15\u0e23. \u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e19\u0e49\u0e33 142 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 1.3 \u0e41\u0e2a\u0e19\u0e44\u0e23\u0e48\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/cbGFO3v0aac?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"682\" src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_6_0-1024x682.jpg\" alt=\"\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e40\u0e23\u0e48\u0e07\u0e41\u0e01\u0e49\u0e41\u0e25\u0e49\u0e07! \u0e1c\u0e38\u0e14 4 \u0e1b\u0e15\u0e23.\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 &quot;\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01-\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23-\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c&quot; \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e19\u0e49\u0e33 142 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e22\u0e34\u0e49\u0e21\u0e23\u0e31\u0e1a 129,500 \u0e44\u0e23\u0e48\" class=\"wp-image-64568\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_6_0-1024x682.jpg 1024w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_6_0-500x333.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_6_0-696x464.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_6_0-1068x712.jpg 1068w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_6_0-630x420.jpg 630w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_6_0.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48 3 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 <strong>\u0e19\u0e32\u0e22\u0e2a\u0e21\u0e08\u0e34\u0e15\u0e10\u0e34\u0e1e\u0e07\u0e28\u0e4c \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e28\u0e32\u0e25 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48 <\/strong><strong>3 \u0e01\u0e23\u0e21\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19<\/strong> \u0e44\u0e14\u0e49\u0e19\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 4 \u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19\u0e43\u0e19\u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 (\u0e1b\u0e15\u0e23.) &#8220;\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01&#8221;, &#8220;\u0e42\u0e04\u0e01\u0e2a\u0e25\u0e38\u0e14&#8221;, &#8220;\u0e1a\u0e32\u0e07\u0e44\u0e1c\u0e48&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e27\u0e31\u0e07\u0e2b\u0e21\u0e32\u0e40\u0e19\u0e48\u0e32\u201d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e01\u0e49\u0e20\u0e31\u0e22\u0e41\u0e25\u0e49\u0e07-\u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21 \u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 <strong>\u0e19\u0e32\u0e22\u0e2a\u0e21\u0e08\u0e34\u0e15\u0e10\u0e34\u0e1e\u0e07\u0e28\u0e4c \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e28\u0e32\u0e25 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48 <\/strong><strong>3<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e01\u0e23\u0e21\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e44\u0e14\u0e49\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e19\u0e49\u0e33\u0e43\u0e19\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19\u0e21\u0e32\u0e42\u0e14\u0e22\u0e15\u0e25\u0e2d\u0e14 \u0e21\u0e35\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e2d\u0e32\u0e17\u0e34 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c, \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e41\u0e04\u0e27\u0e19\u0e49\u0e2d\u0e22\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e41\u0e14\u0e19, \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e14\u0e19\u0e49\u0e33\u0e1c\u0e32\u0e08\u0e38\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e14\u0e19\u0e49\u0e33\u0e19\u0e40\u0e23\u0e28\u0e27\u0e23 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e23\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2d\u0e48\u0e32\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33\u0e44\u0e27\u0e49\u0e44\u0e14\u0e49 10,430.25 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e21\u0e35\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e01\u0e31\u0e01\u0e19\u0e49\u0e33\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e01\u0e25\u0e32\u0e07 (\u0e1b\u0e35 2565-2575) \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e2d\u0e35\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e48\u0e32\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33\u0e19\u0e49\u0e33\u0e1b\u0e32\u0e14 (\u0e20\u0e39\u0e27\u0e31\u0e07\u0e1c\u0e32), \u0e2d\u0e48\u0e32\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33\u0e19\u0e49\u0e33\u0e01\u0e2d\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e32\u0e14\u0e27\u0e48\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e21\u0e35\u0e19\u0e49\u0e33\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 799 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e01\u0e23\u0e21\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e08\u0e36\u0e07\u0e21\u0e35\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e43\u0e0a\u0e49\u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e01\u0e31\u0e01\u0e19\u0e49\u0e33 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2f \u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e02\u0e13\u0e30\u0e19\u0e35\u0e49 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1c\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e43\u0e19\u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 \u0e1b\u0e35 2566-2567 \u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e21\u0e35\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e 7 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e21\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19 \u0e08\u0e33\u0e19\u0e27\u0e19 4 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"562\" src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762660891727.jpg\" alt=\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \" class=\"wp-image-64573\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762660891727.jpg 1000w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762660891727-500x281.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762660891727-696x391.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762660891727-747x420.jpg 747w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<ul>\n<li><strong>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01<\/strong> (\u0e15.\u0e07\u0e34\u0e49\u0e27\u0e07\u0e32\u0e21 \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01)\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30: \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1b\u0e15\u0e23. \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e25\u0e31\u0e14\u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19, \u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e15\u0e23\u0e07 4 \u0e1a\u0e32\u0e19 (\u0e01\u0e27\u0e49\u0e32\u0e07 12.50 \u0e21. \u0e2a\u0e39\u0e07 7.50 \u0e21.) \u0e41\u0e25\u0e30\u0e1d\u0e32\u0e22\u0e1e\u0e31\u0e1a\u0e44\u0e14\u0e49 2 \u0e0a\u0e48\u0e2d\u0e07 (\u0e01\u0e27\u0e49\u0e32\u0e07 15.00 \u0e21. \u0e2a\u0e39\u0e07 4.00 \u0e21.) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e1b\u0e25\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e40\u0e01\u0e47\u0e1a\u0e01\u0e31\u0e01: 44.33 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c: 17,762 \u0e44\u0e23\u0e48 (\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 10 \u0e41\u0e2b\u0e48\u0e07)<\/li>\n\n\n\n<li><strong>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e42\u0e04\u0e01\u0e2a\u0e25\u0e38\u0e14<\/strong> (\u0e15.\u0e42\u0e04\u0e01\u0e2a\u0e25\u0e38\u0e14 \u0e2d.\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e17\u0e38\u0e48\u0e21 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01) \u0e25\u0e31\u0e01\u0e29\u0e13\u0e30: \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1b\u0e15\u0e23. \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e31\u0e49\u0e19\u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19, \u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e15\u0e23\u0e07 4 \u0e1a\u0e32\u0e19 (\u0e01\u0e27\u0e49\u0e32\u0e07 12.50 \u0e21. \u0e2a\u0e39\u0e07 8.50 \u0e21.) \u0e41\u0e25\u0e30\u0e1d\u0e32\u0e22\u0e1e\u0e31\u0e1a\u0e44\u0e14\u0e49 2 \u0e0a\u0e48\u0e2d\u0e07 (\u0e01\u0e27\u0e49\u0e32\u0e07 15.00 \u0e21. \u0e2a\u0e39\u0e07 4.00 \u0e21.) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e1b\u0e25\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e40\u0e01\u0e47\u0e1a\u0e01\u0e31\u0e01: 18.21 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c: 11,365 \u0e44\u0e23\u0e48 (\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 8 \u0e41\u0e2b\u0e48\u0e07)<\/li>\n\n\n\n<li><strong>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e1a\u0e32\u0e07\u0e44\u0e1c\u0e48<\/strong> (\u0e15.\u0e1a\u0e32\u0e07\u0e44\u0e1c\u0e48 \u0e2d.\u0e1a\u0e32\u0e07\u0e21\u0e39\u0e25\u0e19\u0e32\u0e01 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23) \u0e25\u0e31\u0e01\u0e29\u0e13\u0e30: \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1b\u0e15\u0e23. \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e31\u0e49\u0e19\u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19, \u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e15\u0e23\u0e07 4 \u0e1a\u0e32\u0e19 (\u0e01\u0e27\u0e49\u0e32\u0e07 12.50 \u0e21. \u0e2a\u0e39\u0e07 8.50 \u0e21.) \u0e41\u0e25\u0e30\u0e1d\u0e32\u0e22\u0e1e\u0e31\u0e1a\u0e44\u0e14\u0e49 2 \u0e0a\u0e48\u0e2d\u0e07 (\u0e01\u0e27\u0e49\u0e32\u0e07 15.00 \u0e21. \u0e2a\u0e39\u0e07 4.00 \u0e21.) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e1b\u0e25\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e0d\u0e08\u0e23 \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e40\u0e01\u0e47\u0e1a\u0e01\u0e31\u0e01: 37.71 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c: 54,565 \u0e44\u0e23\u0e48 (\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 24 \u0e41\u0e2b\u0e48\u0e07)<\/li>\n\n\n\n<li><strong>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e27\u0e31\u0e07\u0e2b\u0e21\u0e32\u0e40\u0e19\u0e48\u0e32<\/strong> (\u0e15.\u0e17\u0e31\u0e1a\u0e01\u0e24\u0e0a \u0e2d.\u0e0a\u0e38\u0e21\u0e41\u0e2a\u0e07 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c) \u0e25\u0e31\u0e01\u0e29\u0e13\u0e30: \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1b\u0e15\u0e23. \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e25\u0e31\u0e14\u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19, \u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e15\u0e23\u0e07 4 \u0e1a\u0e32\u0e19 (\u0e01\u0e27\u0e49\u0e32\u0e07 12.50 \u0e21. \u0e2a\u0e39\u0e07 8.50 \u0e21.) \u0e41\u0e25\u0e30\u0e1d\u0e32\u0e22\u0e1e\u0e31\u0e1a\u0e44\u0e14\u0e49 2 \u0e0a\u0e48\u0e2d\u0e07 (\u0e01\u0e27\u0e49\u0e32\u0e07 15.00 \u0e21. \u0e2a\u0e39\u0e07 4.00 \u0e21.) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e1b\u0e25\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e0d\u0e08\u0e23 \u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e40\u0e01\u0e47\u0e1a\u0e01\u0e31\u0e01: 41.94 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c: 45,749 \u0e44\u0e23\u0e48 (\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 15 \u0e41\u0e2b\u0e48\u0e07)<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"550\" src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762660911738.jpg\" alt=\"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e27\u0e31\u0e07\u0e2b\u0e21\u0e32\u0e40\u0e19\u0e48\u0e32\" class=\"wp-image-64574\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762660911738.jpg 1000w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762660911738-500x275.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762660911738-696x383.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762660911738-764x420.jpg 764w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p><strong>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 <\/strong><strong>4 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e43\u0e19\u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e01\u0e27\u0e48\u0e32 142<\/strong><strong>.<\/strong><strong>19 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21 129,441 \u0e44\u0e23\u0e48<\/strong><strong> <\/strong><strong><\/strong><\/p>\n\n\n\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e44\u0e14\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e42\u0e14\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2f \u0e17\u0e31\u0e49\u0e07\u0e40\u0e27\u0e17\u0e35 \u0e1b\u0e15\u0e23.\u0e42\u0e04\u0e01\u0e2a\u0e25\u0e38\u0e14 \u0e41\u0e25\u0e30 \u0e1b\u0e15\u0e23.\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 6 \u0e1e.\u0e22.68 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35 <strong>\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e0d\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21<\/strong>&nbsp;\u0e0b\u0e36\u0e48\u0e07\u0e17\u0e31\u0e49\u0e07 2 \u0e40\u0e27\u0e17\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e43\u0e19\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u0e41\u0e25\u0e30 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1c\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e43\u0e19\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48 3 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e19\u0e49\u0e33\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e14\u0e22 \u0e19\u0e32\u0e22\u0e0a\u0e33\u0e19\u0e32\u0e0d \u0e0a\u0e39\u0e40\u0e17\u0e35\u0e48\u0e22\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 , \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33 \u0e17\u0e31\u0e49\u0e07\u0e15\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e01\u0e25\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e1b\u0e25\u0e32\u0e22\u0e19\u0e49\u0e33<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"682\" src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_7_0-1024x682.jpg\" alt=\"\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e0d\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e1a\u0e32\u0e23\u0e21\u0e35\" class=\"wp-image-64575\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_7_0-1024x682.jpg 1024w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_7_0-500x333.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_7_0-696x464.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_7_0-1068x712.jpg 1068w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_7_0-630x420.jpg 630w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_7_0.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e0d\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 &#8220;\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\u0e21\u0e35\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e2a\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e37\u0e2d\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 \u0e41\u0e15\u0e48\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e01\u0e47\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e17\u0e01\u0e20\u0e31\u0e22\u0e41\u0e25\u0e30\u0e20\u0e31\u0e22\u0e41\u0e25\u0e49\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e16\u0e49\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e47\u0e08 \u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e20\u0e31\u0e22\u0e41\u0e25\u0e49\u0e07 \u0e43\u0e19\u0e24\u0e14\u0e39\u0e1d\u0e19\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25\u0e19\u0e49\u0e33\u0e44\u0e14\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e19\u0e49\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e21\u0e32\u0e01&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-9-16 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u0e44\u0e01\u0e48\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e40\u0e23\u0e28\u0e27\u0e23\u0e08\u0e30\u0e21\u0e32\u0e2a\u0e16\u0e34\u0e15\u0e17\u0e35\u0e48\u0e1b\u0e15\u0e23.\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48? #\u0e01\u0e23\u0e21\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\" width=\"540\" height=\"960\" src=\"https:\/\/www.youtube.com\/embed\/mRvOgtwef2U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"560\" src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762676815739.jpg\" alt=\"\u0e19\u0e32\u0e22\u0e21\u0e19\u0e15\u0e4c\u0e0a\u0e31\u0e22 \u0e27\u0e34\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e18\u0e19\u0e32\u0e12\u0e22\u0e4c \" class=\"wp-image-64576\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762676815739.jpg 1000w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762676815739-500x280.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762676815739-696x390.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762676815739-750x420.jpg 750w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\"><strong><em>\u0e19\u0e32\u0e22\u0e21\u0e19\u0e15\u0e4c\u0e0a\u0e31\u0e22 \u0e27\u0e34\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e18\u0e19\u0e32\u0e12\u0e22\u0e4c (\u0e04\u0e19\u0e01\u0e25\u0e32\u0e07)<\/em><\/strong><\/figcaption><\/figure>\n\n\n\n<p><strong>\u0e19\u0e32\u0e22\u0e21\u0e19\u0e15\u0e4c\u0e0a\u0e31\u0e22 \u0e27\u0e34\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e18\u0e19\u0e32\u0e12\u0e22\u0e4c \u0e19\u0e32\u0e22\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 &#8220;\u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07 (\u0e1b\u0e15\u0e23.\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01) \u0e21\u0e35\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e0a\u0e48\u0e27\u0e07\u0e24\u0e14\u0e39\u0e41\u0e25\u0e49\u0e07 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e15\u0e25\u0e34\u0e48\u0e07\u0e1e\u0e31\u0e07 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33\u0e14\u0e34\u0e1a\u0e21\u0e32\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 (\u0e15\u0e30\u0e01\u0e2d\u0e19\u0e25\u0e14\u0e25\u0e07) \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15&#8221; \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33 (\u0e15\u0e49\u0e19\u0e19\u0e49\u0e33-\u0e01\u0e25\u0e32\u0e07\u0e19\u0e49\u0e33-\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e49\u0e33)&nbsp;\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 &#8220;\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e02\u0e32\u0e14\u0e19\u0e49\u0e33\u0e43\u0e19\u0e24\u0e14\u0e39\u0e41\u0e25\u0e49\u0e07 \u0e17\u0e33\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e32\u0e01\u0e21\u0e35\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e16\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e02\u0e32\u0e14\u0e19\u0e49\u0e33 \u0e16\u0e49\u0e32\u0e21\u0e35\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e31\u0e49\u0e19\u0e1a\u0e31\u0e19\u0e44\u0e14 \u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e2b\u0e25\u0e32\u0e19\u0e08\u0e30\u0e44\u0e21\u0e48\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e19\u0e49\u0e33 \u0e23\u0e2d\u0e04\u0e2d\u0e22\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e21\u0e32\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e41\u0e25\u0e30\u0e14\u0e35\u0e43\u0e08\u0e21\u0e32\u0e01 \u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e01\u0e23\u0e21\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"666\" src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_8_0-1.jpg\" alt=\"\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e40\u0e23\u0e48\u0e07\u0e41\u0e01\u0e49\u0e41\u0e25\u0e49\u0e07! \u0e1c\u0e38\u0e14 4 \u0e1b\u0e15\u0e23.\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 &quot;\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01-\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23-\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c&quot; \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e19\u0e49\u0e33 142 \u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e22\u0e34\u0e49\u0e21\u0e23\u0e31\u0e1a 129,500 \u0e44\u0e23\u0e48\" class=\"wp-image-64571\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_8_0-1.jpg 1000w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_8_0-1-500x333.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_8_0-1-696x464.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_8_0-1-631x420.jpg 631w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\"><em><strong>\u0e19\u0e32\u0e22\u0e2a\u0e21\u0e08\u0e34\u0e15\u0e10\u0e34\u0e1e\u0e07\u0e28\u0e4c \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e28\u0e32\u0e25 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07 \u0e1b\u0e15\u0e23. \u0e17\u0e31\u0e49\u0e07 4 \u0e41\u0e2b\u0e48\u0e07 <\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<p><strong>\u0e19\u0e32\u0e22\u0e2a\u0e21\u0e08\u0e34\u0e15\u0e10\u0e34\u0e1e\u0e07\u0e28\u0e4c \u0e2d\u0e33\u0e19\u0e32\u0e08\u0e28\u0e32\u0e25 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48 <\/strong><strong>3<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e2a\u0e23\u0e38\u0e1b\u0e27\u0e48\u0e32 &#8220;\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e02\u0e2d\u0e07 \u0e1b\u0e15\u0e23. \u0e17\u0e31\u0e49\u0e07 4 \u0e41\u0e2b\u0e48\u0e07 \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33\u0e44\u0e27\u0e49\u0e43\u0e19\u0e25\u0e33\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e1d\u0e19\u0e17\u0e34\u0e49\u0e07\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e25\u0e30\u0e24\u0e14\u0e39\u0e41\u0e25\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e15\u0e23. \u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e46 \u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e17\u0e14\u0e19\u0e49\u0e33\u0e43\u0e2b\u0e49\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e21\u0e49\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e23\u0e27\u0e21 140 \u0e01\u0e27\u0e48\u0e32\u0e25\u0e49\u0e32\u0e19 \u0e25\u0e1a.\u0e21. \u0e2d\u0e32\u0e08\u0e14\u0e39\u0e44\u0e21\u0e48\u0e40\u0e22\u0e2d\u0e30 \u0e41\u0e15\u0e48 \u0e1b\u0e15\u0e23. \u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e08\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e2d\u0e48\u0e32\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e25\u0e14\u0e25\u0e07\u0e01\u0e47\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e19\u0e49\u0e33\u0e08\u0e32\u0e01\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19\u0e21\u0e32\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e14\u0e49\u0e32\u0e19\u0e19\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e21\u0e35\u0e19\u0e49\u0e33\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e35<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"682\" src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_1_0-1024x682.jpg\" alt=\"\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e43\u0e19\u0e08\u0e38\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e15\u0e23.\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\" class=\"wp-image-64566\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_1_0-1024x682.jpg 1024w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_1_0-500x333.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_1_0-696x464.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_1_0-1068x712.jpg 1068w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_1_0-630x420.jpg 630w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/LINE_ALBUM_6-7-\u0e1e.\u0e22.68_251108_1_0.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em><strong>\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e43\u0e19\u0e08\u0e38\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e15\u0e23.\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e21\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e17\u0e35\u0e48 \u0e08\u0e38\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a\u0e17\u0e35\u0e48 6 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e04\u0e37\u0e2d \u0e19\u0e32\u0e22\u0e0a\u0e33\u0e19\u0e32\u0e0d \u0e0a\u0e39\u0e40\u0e17\u0e35\u0e48\u0e22\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e2a\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e04\u0e37\u0e2d\u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e1a\u0e38\u0e0d\u0e23\u0e31\u0e01\u0e0a\u0e32\u0e15\u0e34 \u0e2d\u0e14\u0e35\u0e15\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a\u0e17\u0e35\u0e48 6 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e43\u0e19\u0e08\u0e38\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e17\u0e49\u0e32\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e31\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a\u0e17\u0e35\u0e48 6 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e2a\u0e27\u0e19 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e38\u0e02\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\u0e41\u0e25\u0e30 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19(\u0e15\u0e49\u0e19\u0e19\u0e49\u0e33) \u0e19\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10 \u0e28\u0e23\u0e35\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e19\u0e38\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19(\u0e01\u0e25\u0e32\u0e07\u0e19\u0e49\u0e33) \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2a\u0e21\u0e32\u0e19 \u0e01\u0e31\u0e19\u0e17\u0e32 \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19\u0e20\u0e32\u0e04\u0e40\u0e2b\u0e19\u0e37\u0e2d(\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e49\u0e33) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e04\u0e25\u0e34\u0e1b\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e49\u0e32\u0e22\u0e19\u0e35\u0e49<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"577\" src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762677828686.jpg\" alt=\"3 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19-\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33 \u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19\" class=\"wp-image-64578\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762677828686.jpg 1000w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762677828686-500x289.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762677828686-696x402.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2025\/11\/messageImage_1762677828686-728x420.jpg 728w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">3 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19-\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33 \u0e25\u0e38\u0e48\u0e21\u0e19\u0e49\u0e33\u0e19\u0e48\u0e32\u0e19<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e02\u0e48\u0e32\u0e27\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\/\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 (6-7 \u0e1e.\u0e22.68) &#8211; \u0e01\u0e23\u0e21\u0e0a\u0e25\u0e1b\u0e23\u0e30 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":64564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[51,48],"tags":[1771,19728,19729,19727],"_links":{"self":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts\/64563"}],"collection":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/comments?post=64563"}],"version-history":[{"count":3,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts\/64563\/revisions"}],"predecessor-version":[{"id":64581,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts\/64563\/revisions\/64581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/media\/64564"}],"wp:attachment":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/media?parent=64563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/categories?post=64563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/tags?post=64563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}