{"id":27953,"date":"2020-05-13T12:54:26","date_gmt":"2020-05-13T05:54:26","guid":{"rendered":"https:\/\/www.kasetkaoklai.com\/home\/?p=27953"},"modified":"2020-05-13T12:54:26","modified_gmt":"2020-05-13T05:54:26","slug":"%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%94%e0%b8%b5-%e0%b8%87%e0%b8%9a%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%a2%e0%b8%b2%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3%e0%b8%81","status":"publish","type":"post","link":"https:\/\/www.kasetkaoklai.com\/home\/2020\/05\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b8%94%e0%b8%b5-%e0%b8%87%e0%b8%9a%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%a2%e0%b8%b2%e0%b9%80%e0%b8%81%e0%b8%a9%e0%b8%95%e0%b8%a3%e0%b8%81\/","title":{"rendered":"\u0e02\u0e48\u0e32\u0e27\u0e14\u0e35!! \u0e07\u0e1a\u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 150,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e16\u0e36\u0e07\u0e21\u0e37\u0e2d \u0e2a\u0e28\u0e01.\u0e41\u0e25\u0e49\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e48\u0e32\u0e22\u0e07\u0e27\u0e14\u0e41\u0e23\u0e01 15 \u0e1e.\u0e04. \u0e19\u0e35\u0e49"},"content":{"rendered":"<p><strong>\u0e02\u0e48\u0e32\u0e27\u0e14\u0e35!! \u0e07\u0e1a <\/strong><strong>150,000<\/strong><strong> \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e16\u0e36\u0e07\u0e21\u0e37\u0e2d \u0e2a\u0e28\u0e01. \u0e41\u0e25\u0e49\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e31\u0e48\u0e07\u0e08\u0e48\u0e32\u0e22\u0e40\u0e0a\u0e47\u0e04 \u0e18.\u0e01.\u0e2a. \u0e07\u0e27\u0e14\u0e41\u0e23\u0e01 \u0e22\u0e37\u0e19\u0e22\u0e31\u0e19 <\/strong><strong>15<\/strong><strong> \u0e1e.\u0e04. \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 <\/strong><strong>1<\/strong><strong> \u0e25\u0e49\u0e32\u0e19\u0e23\u0e32\u0e22\u0e41\u0e23\u0e01 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32 <\/strong><strong>5,000<\/strong><strong> \u0e1a\u0e32\u0e17 \u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19<\/strong><\/p>\n<figure id=\"attachment_27958\" aria-describedby=\"caption-attachment-27958\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-27958\" src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2020\/05\/S__63987719.jpg\" alt=\"\u0e14\u0e23.\u0e40\u0e09\u0e25\u0e34\u0e21\u0e0a\u0e31\u0e22 \u0e28\u0e23\u0e35\u0e2d\u0e48\u0e2d\u0e19 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \" width=\"750\" height=\"498\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2020\/05\/S__63987719.jpg 750w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2020\/05\/S__63987719-500x332.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2020\/05\/S__63987719-696x462.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2020\/05\/S__63987719-633x420.jpg 633w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-27958\" class=\"wp-caption-text\">\u0e14\u0e23.\u0e40\u0e09\u0e25\u0e34\u0e21\u0e0a\u0e31\u0e22 \u0e28\u0e23\u0e35\u0e2d\u0e48\u0e2d\u0e19 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c<\/figcaption><\/figure>\n<p><strong>\u0e14\u0e23.\u0e40\u0e09\u0e25\u0e34\u0e21\u0e0a\u0e31\u0e22 \u0e28\u0e23\u0e35\u0e2d\u0e48\u0e2d\u0e19<\/strong> \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e37\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e23 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32 2019 \u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49 <strong>\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 (\u0e2a\u0e28\u0e01.) <\/strong>\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e19\u0e32\u0e22\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e31\u0e14\u0e01\u0e23\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e48\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e42\u0e14\u0e22\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e19\u0e27\u0e19 5,000 \u0e1a\u0e32\u0e17 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 3 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21-\u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2563 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 10 \u0e25\u0e49\u0e32\u0e19\u0e23\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e0b\u0e49\u0e33\u0e0b\u0e49\u0e2d\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e17\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e23\u0e27\u0e21\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2f \u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 150,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u00a0 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e07\u0e34\u0e19\u0e01\u0e39\u0e49\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e01.\u0e43\u0e2b\u0e49\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e01\u0e39\u0e49\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32 \u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32 2019 \u0e1e.\u0e28. 2563 \u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 150,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17<\/p>\n<figure id=\"attachment_27955\" aria-describedby=\"caption-attachment-27955\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-27955\" src=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2020\/05\/S__193495048.jpg\" alt=\"\u0e02\u0e48\u0e32\u0e27\u0e14\u0e35!! \u0e07\u0e1a\u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 150,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e16\u0e36\u0e07\u0e21\u0e37\u0e2d \u0e2a\u0e28\u0e01.\u0e41\u0e25\u0e49\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e48\u0e32\u0e22\u0e07\u0e27\u0e14\u0e41\u0e23\u0e01 15 \u0e1e.\u0e04. \u0e19\u0e35\u0e49\" width=\"1000\" height=\"666\" srcset=\"https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2020\/05\/S__193495048.jpg 1000w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2020\/05\/S__193495048-500x333.jpg 500w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2020\/05\/S__193495048-696x464.jpg 696w, https:\/\/www.kasetkaoklai.com\/home\/wp-content\/uploads\/2020\/05\/S__193495048-631x420.jpg 631w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-27955\" class=\"wp-caption-text\">\u0e19\u0e32\u0e22\u0e23\u0e30\u0e1e\u0e35\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e08\u0e31\u0e19\u0e17\u0e23\u0e28\u0e23\u0e35\u0e27\u0e07\u0e28\u0e4c \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e28\u0e01.<\/figcaption><\/figure>\n<p><strong>\u0e19\u0e32\u0e22\u0e23\u0e30\u0e1e\u0e35\u0e20\u0e31\u0e17\u0e23\u0e4c\u00a0 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e28\u0e23\u0e35\u0e27\u0e07\u0e28\u0e4c<\/strong>\u00a0\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e28\u0e01. \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e19\u0e32\u0e22\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e02\u0e13\u0e30\u0e19\u0e35\u0e49 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e44\u0e14\u0e49\u0e42\u0e2d\u0e19\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e43\u0e2b\u0e49 \u0e2a\u0e28\u0e01. \u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e33\u0e19\u0e27\u0e19 150,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e42\u0e14\u0e22 \u0e2a\u0e28\u0e01. \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e0a\u0e47\u0e04\u0e43\u0e2b\u0e49 \u0e18.\u0e01.\u0e2a.\u00a0 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2563 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e1a\u0e41\u0e23\u0e01 \u0e08\u0e33\u0e19\u0e27\u0e19 25,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30 \u0e23\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 25,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u00a0 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e08\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e18.\u0e01.\u0e2a. \u0e17\u0e38\u0e01\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e23\u0e27\u0e21 6 \u0e07\u0e27\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49 \u0e18.\u0e01.\u0e2a. \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e15\u0e48\u0e2d\u0e44\u0e1b\u00a0 \u0e0b\u0e36\u0e48\u0e07 \u0e18.\u0e01.\u0e2a. \u0e08\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e23\u0e2d\u0e1a\u0e41\u0e23\u0e01\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 15 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e25\u0e49\u0e32\u0e19\u0e23\u0e32\u0e22\u00a0 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e07\u0e34\u0e19 5,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e46 \u0e25\u0e30 1 \u0e25\u0e49\u0e32\u0e19\u0e23\u0e32\u0e22 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e01\u0e23\u0e13\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e40\u0e07\u0e34\u0e19\u0e1d\u0e32\u0e01\u0e01\u0e31\u0e1a \u0e18.\u0e01.\u0e2a. \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e08\u0e49\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e40\u0e07\u0e34\u0e19\u0e1d\u0e32\u0e01\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e1a\u0e31\u0e15\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e40\u0e25\u0e02\u0e17\u0e35\u0e48\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e40\u0e07\u0e34\u0e19\u0e1d\u0e32\u0e01\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c <a href=\"http:\/\/www.\u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23.com\">www.\u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23.com<\/a><\/p>\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e2a\u0e28\u0e01. \u0e44\u0e14\u0e49\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e23\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e17\u0e18\u0e23\u0e13\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32 2019 (COVID-19) \u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e41\u0e08\u0e49\u0e07\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e17\u0e23\u0e32\u0e1a\u0e42\u0e14\u0e22\u0e40\u0e23\u0e47\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e02\u0e48\u0e32\u0e27\u0e14\u0e35!! \u0e07\u0e1a 150,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e16\u0e36\u0e07\u0e21\u0e37\u0e2d \u0e2a\u0e28\u0e01. \u0e41\u0e25\u0e49\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e31\u0e48\u0e07\u0e08 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[51,48],"tags":[10926,10927,10870,10928,10929],"_links":{"self":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts\/27953"}],"collection":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/comments?post=27953"}],"version-history":[{"count":2,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts\/27953\/revisions"}],"predecessor-version":[{"id":27960,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/posts\/27953\/revisions\/27960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/media\/27957"}],"wp:attachment":[{"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/media?parent=27953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/categories?post=27953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kasetkaoklai.com\/home\/wp-json\/wp\/v2\/tags?post=27953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}